{"id":149583,"date":"2025-12-01T14:22:13","date_gmt":"2025-12-01T14:22:13","guid":{"rendered":"https:\/\/www.equitat.org\/blog\/ciutats-comunitats-educadores-educacio-360\/"},"modified":"2025-12-03T15:28:37","modified_gmt":"2025-12-03T15:28:37","slug":"ciutats-comunitats-educadores-educacio-360","status":"publish","type":"post","link":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360","title":{"rendered":"De Ciudad Educadora a Comunidades Educadoras: el futuro que ya est\u00e1 en marcha"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Treinta a\u00f1os que han cambiado el marco: la ciudad como agente educativo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hace m\u00e1s de tres d\u00e9cadas, la <a href=\"https:\/\/www.edcities.org\/ca\/wp-content\/uploads\/sites\/6\/2020\/12\/CAT_Carta-2.pdf\">Carta de Ciudades Educadoras<\/a> formul\u00f3 una idea que, con el tiempo, se ha convertido en una evidencia: \u201cla educaci\u00f3n trasciende los muros de la escuela para impregnar a toda la ciudad\u201d. Aquella formulaci\u00f3n aparentemente sencilla abri\u00f3 un nuevo campo conceptual que entend\u00eda la ciudad (sus espacios, servicios, relaciones, instituciones y ciudadan\u00eda) como un ecosistema educativo permanente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La innovaci\u00f3n no fue s\u00f3lo pol\u00edtica y t\u00e9cnica, sino sobre todo <strong>cultural<\/strong>.Desplaz\u00f3 la mirada de la escuela como \u00fanico centro de gravedad educativo a una idea de ciudad que tambi\u00e9n educa, que acoge la diversidad, que promueve v\u00ednculos y que hace de la <strong>convivencia y los aprendizajes una tarea colectiva.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este cambio de perspectiva tuvo una consecuencia decisiva: <strong>ampliar el derecho a la educaci\u00f3n m\u00e1s all\u00e1 de la ense\u00f1anza obligatoria<\/strong>. Asent\u00f3 las bases de lo que hoy llamamos educaci\u00f3n 360.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00abLos tiempos y espacios fuera escuela son hoy m\u00e1s determinantes que nunca para el crecimiento de ni\u00f1os y adolescentes\u00bb<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Treinta y cinco a\u00f1os despu\u00e9s, ese movimiento ha demostrado estar no s\u00f3lo vigente, sino imprescindible. El momento actual, marcado por profundas desigualdades, crisis ecosocial, fragilidad democr\u00e1tica y nuevas formas de socializaci\u00f3n, pide un paso m\u00e1s all\u00e1. Y este paso, hoy, se enriquece con la perspectiva de <strong>comunidades educadoras.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El centro es hoy la comunidad: una realidad que ya existe<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No hace falta imaginar escenarios futuros, los fundamentos de <strong>las comunidades educadoras ya est\u00e1n aqu\u00ed<\/strong>. Cientos de municipios, entidades, escuelas, familias y profesionales est\u00e1n convirtiendo barrios y pueblos en escenarios educativos llenos de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta realidad se ha hecho especialmente visible en espacios de reflexi\u00f3n colectiva como la <a href=\"https:\/\/educacio360.cat\/yayo-herrero-ens-cal-teixir-relacions-denses-i-comunitaries-als-espais-als-marges-com-el-lleure-dels-infants-i-joves\/\">7\u00aa Jornada Anual de Educaci\u00f3n 360<\/a>, donde la conversaci\u00f3n central con Yayo Herrero puso palabras a una intuici\u00f3n compartida: la educaci\u00f3n que realmente transforma es la que arraiga en el territorio y se construye desde la comunidad.En este contexto, Yayo Herrero tambi\u00e9n hizo una reflexi\u00f3n clave: \u00abel ocio y el tiempo libre, o lo ocupas o te lo ocupan\u00bb. Esta afirmaci\u00f3n sintetiza un diagn\u00f3stico muy actual que muestra que <strong>el tiempo y los espacios fuera escuela son hoy m\u00e1s determinantes que nunca para el crecimiento de los ni\u00f1os y adolescentes<\/strong>. Si no los llenamos de amistades, actividades significativas y referentes adultos positivos, estos espacios est\u00e1n r\u00e1pidamente ocupados por otras fuerzas que promueven el aislamiento social, la soledad, el sedentarismo o los mensajes de odio.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"700\" height=\"400\" src=\"https:\/\/www.youtube.com\/embed\/khiT9EYLQ6s?si=SQ5fprMjGqx_65zp\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso Yayo insiste en que hay que <strong>\u201ctejer relaciones densas y comunitarias en los espacios en los m\u00e1rgenes\u201d<\/strong>. Porque el ocio educativo no es s\u00f3lo una actividad complementaria: es el espacio donde muchos ni\u00f1os descubren qui\u00e9nes son y qu\u00e9 les gusta, d\u00f3nde encuentran sus primeros c\u00edrculos de cari\u00f1o, y d\u00f3nde experimentan formas de participaci\u00f3n y de vida colectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta forma de entender el fueraescuela como un espacio educativo lleno de potencial ya se est\u00e1 desplegando en muchos territorios. Las experiencias compartidas en la Feria 360 de la Jornada Anual son un buen ejemplo de ello: proyectos coliderados entre ayuntamientos, entidades y centros educativos que fortalecen los v\u00ednculos comunitarios y convierten el ocio en un bien com\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCuando la\u00a0<a href=\"https:\/\/www.edcities.org\/ca\/wp-content\/uploads\/sites\/6\/2025\/10\/Declaraci%C3%B3-del-Dia-Internacional-de-la-Ciutat-Educadora-2025-CAT.pdf\">Declaraci\u00f3n del D\u00eda Internacional de la Ciudad Educadora 2025<\/a>\u00a0afirma que\u00a0\u201cla infancia es protagonista y constructora del futuro\u201d\u00a0est\u00e1 describiendo pr\u00e1cticas que hoy ya se despliegan en muchos territorios\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las comunidades educadoras, pues, <strong>ya existen.<\/strong> El reto no es inventarlas, sino reconocerlas, reforzarlas y dar la estabilidad estructural para que ese potencial comunitario llegue a todos los ni\u00f1os y adolescentes.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"700\" height=\"400\" src=\"https:\/\/www.youtube.com\/embed\/Ra6DQh1038o?si=Va55MLYOtHfB_yKp\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El legado de Ciudades Educadoras que ha hecho posible este salto<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019evoluci\u00f3 cap a les comunitats educadores \u00e9s possible perqu\u00e8 s\u2019inscriu en una genealogia marcada pel moviment de Ciutats E<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La evoluci\u00f3n hacia las comunidades educadoras es posible porque se inscribe en una genealog\u00eda marcada por el movimiento de Ciudades Educadoras. De hecho, muchas de las ideas que hoy reivindicamos desde la visi\u00f3n de educaci\u00f3n a tiempo completo ya se encuentran en la Carta y en las diferentes declaraciones que se han ido haciendo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la ciudad como agente educativo permanente,<\/li>\n\n\n\n<li>la importancia de generar conciencia comunitaria y habilidades para organizar la vida en com\u00fan en condiciones de igualdad y justicia,<\/li>\n\n\n\n<li>el compromiso de garantizar la participaci\u00f3n de la infancia y la adolescencia en la vida comunitaria,<\/li>\n\n\n\n<li>la responsabilidad colectiva de sostener la vida.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la <a href=\"https:\/\/www.edcities.org\/ca\/wp-content\/uploads\/sites\/6\/2025\/10\/Declaraci%C3%B3-del-Dia-Internacional-de-la-Ciutat-Educadora-2025-CAT.pdf\">Declaraci\u00f3n del D\u00eda Internacional de la Ciudad Educadora 2025<\/a> afirma que \u201cla infancia es protagonista y constructora del futuro\u201d, no hace s\u00f3lo una declaraci\u00f3n de principios, est\u00e1 describiendo pr\u00e1cticas que hoy ya se despliegan en muchos territorios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este marco conceptual basado en tres elementos clave: la ciudad como ecosistema, la comunidad como sujeto y la infancia y adolescencia como agentes que ejercen su derecho a participar con equidad, es lo que ha permitido que iniciativas como la <a href=\"https:\/\/educacio360.cat\/\">Alianza Educaci\u00f3n 360<\/a> arraigaran y crecieran. Sin ese cambio de mirada de los a\u00f1os noventa, hoy ser\u00eda imposible hablar de comunidades educadoras como presente y como horizonte compartido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora sabemos que\u00a0<strong>educar desde la comunidad no s\u00f3lo es posible, es imprescindible.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Lo que ya est\u00e1 pasando: barrios que educan, pol\u00edticas que cambian, comunidades que cuidan<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El paso hacia las comunidades educadoras no es s\u00f3lo una tendencia emergente, es un <strong>cambio que tiene reconocimiento institucional, avances normativos y formas concretas de pol\u00edtica p\u00fablica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En muchas ciudades y pueblos, la transformaci\u00f3n educadora se hace visible en la proximidad: calles pacificadas, entornos escolares seguros, espacios p\u00fablicos con vocaci\u00f3n educativa, equipamientos que se convierten en nodos comunitarios y redes de entidades que articulan oportunidades educativas fueraescuela. Los barrios y villas se han convertido en la escala clave para entender c\u00f3mo los ni\u00f1os y adolescentes viven su derecho a la educaci\u00f3n ampliada y que incluye desde el trayecto a pie a la escuela, al tiempo en el parque o en la biblioteca, o las actividades en el casal, en el esparcimiento o en experiencias culturales y deportivas que conectan agentes diversos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00abLa educaci\u00f3n comunitaria o 360 no es una cuesti\u00f3n voluntarista, es una pol\u00edtica necesaria y una responsabilidad p\u00fablica\u00bb<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esta mirada reconoce que las oportunidades educativas se construyen en el tiempo y en el espacio cotidiano y es un profundo avance del modelo educativo del pa\u00eds. Un salto impensable hace s\u00f3lo unas d\u00e9cadas que ha hecho posible que la ciudad y el pueblo se reconozcan como ecosistemas educativos y que el pa\u00eds asuma que el ocio educativo no puede quedar al margen del derecho a la educaci\u00f3n, tal y como confirma el articulado de la Ley de Educaci\u00f3n de Catalu\u00f1a (12\/2002 2012). la&nbsp;Ley de los Derechos y Oportunidades en la Infancia y la Adolescencia&nbsp;(14\/2010 art. 57 y 58). Estos marcos normativos abren la puerta a una nueva forma de entender las pol\u00edticas educativas, ya no centradas s\u00f3lo en la escuela, sino en la globalidad de oportunidades que ni\u00f1os y adolescentes deben poder vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la\u00a0<strong>S\u00edndica de Greuges<\/strong>\u00a0ha sido expl\u00edcita en esta misma direcci\u00f3n en el informe\u00a0<em><strong><a href=\"https:\/\/www.sindic.cat\/site\/unitFiles\/10674\/Informe%20lleure%20educatiu_mars_25_sencer_def.pdf\">La universalizaci\u00f3n del ocio educativo en Catalu\u00f1a<\/a>,<\/strong><\/em> que pone cifras y urgencia a lo que muchos territorios ya ven cada d\u00eda: las desigualdades en el acceso a las actividades fueraescuela son una de las brechas educativas m\u00e1s profundas y m\u00e1s injustas. Por eso, <strong>universalizar el ocio es, literalmente, una condici\u00f3n para garantizar la equidad educativa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos reconocimientos institucionales muestran que\u00a0l<strong>a educaci\u00f3n comunitaria o 360 no es una cuesti\u00f3n voluntarista, es una pol\u00edtica necesaria y una responsabilidad p\u00fablica.<\/strong> Este cambio normativo e institucional converge con una realidad de base muy potente: en todo el territorio, <strong>hay comunidades que ya educan,<\/strong> que cuidan y sostienen v\u00ednculos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Hacer estructural lo que ya ocurre: pol\u00edticas que consolidan comunidades educadoras<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No partimos de un vac\u00edo:\u00a0<strong>partimos de un legado potente y de un presente activo<\/strong>. El reto de ahora es que avanzar en el derecho ampliado a la educaci\u00f3n con comunidades educadoras no dependa s\u00f3lo de la voluntad local, de la capacidad organizativa o de la solidez de las redes de un territorio. Es necesario que las pol\u00edticas p\u00fablicas generen las condiciones para que en todas las comunidades puedan poner al alcance oportunidades para el ocio educativo de ni\u00f1os, ni\u00f1as y adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto implica dar continuidad a lo que ya estamos viendo que funciona, y hacerlo desde una l\u00f3gica de derechos. Hacer estructural esta mirada significa avanzar en <a href=\"https:\/\/educacio360.cat\/maria-truno-universalitzar-el-menjador-escolar-les-extraescolars-i-el-lleure-destiu-es-estrategic-i-assumible-amb-el-6-a-leducacio\/\">propuestas concretas como las que la Alianza Educaci\u00f3n 360 ya ha puesto sobre la mesa del Parlamento de Catalu\u00f1a<\/a> para priorizar en la futura ley por la inversi\u00f3n del 6% del PIB en educaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asegurar un <strong>m\u00ednimo de 2 tardes de actividades extraescolares a todos los ni\u00f1os y adolescentes<\/strong>, a trav\u00e9s de ampliar planes educativos de entorno y de incorporar las extraescolares a las \u201cmochilas escolares\u201d del Pacto contra la segregaci\u00f3n.<\/li>\n\n\n\n<li><strong>Garantizar 2 semanas de actividades de verano<\/strong> para todos los ni\u00f1os y adolescentes, empezando por los que crecen en situaci\u00f3n de pobreza, con una medida de pa\u00eds y al mismo tiempo, consolidando planes de verano para reducir desigualdades.<\/li>\n\n\n\n<li><strong>Universalizar el espacio mediod\u00eda como tiempo educativo y de bienestar<\/strong> que garantiza comidas saludables y entorno educativo para todos los ni\u00f1os y tambi\u00e9n adolescentes en todas las escuelas e institutos.<\/li>\n\n\n\n<li><strong>Invertir para dignificar y adecuar el parque escolar p\u00fablico<\/strong> (climatizar, naturalizar, reformar, pintar, etc.) para que los centros educativos sean, a la vez, equipamientos comunitarios abiertos en el barrio para usos diversos como infraestructura social fundamental tambi\u00e9n para el ocio.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas propuestas no inventan nada nuevo:\u00a0<strong>dan una escala sist\u00e9mica y de pa\u00eds a pr\u00e1cticas locales que ya existen<\/strong>, que ya transforman ciudades, barrios y pueblos. Y, sobre todo, hacen posible que el derecho a una educaci\u00f3n ampliada no dependa de d\u00f3nde vives o de tu familia, sino que sea una garant\u00eda compartida por todas partes que no deje a nadie atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avanzar hacia este modelo despliega el potencial del movimiento de Ciudades Educadoras. Si hace m\u00e1s de treinta a\u00f1os la Carta abri\u00f3 la puerta a entender la ciudad como ecosistema educativo, hoy este mismo esp\u00edritu nos empuja a reconocer que este ecosistema se construye desde la comunidad y que debe dotarse de estructura, recursos y estabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacerlo es una apuesta por la cohesi\u00f3n social, por la igualdad de oportunidades y por una educaci\u00f3n que sostiene la vida y fortalece la democracia. En definitiva, es consolidar lo que muchas comunidades ya hacen cada d\u00eda:\u00a0<strong>educar desde el territorio para garantizar infancias y adolescencias m\u00e1s libres, con m\u00e1s v\u00ednculos comunitarios y llenas de posibilidades.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Treinta a\u00f1os que han cambiado el marco: la ciudad como agente educativo Hace m\u00e1s de tres d\u00e9cadas, la Carta de Ciudades Educadoras formul\u00f3 una idea que, con el tiempo, se ha convertido en una evidencia: \u201cla educaci\u00f3n trasciende los muros de la escuela para impregnar a toda la ciudad\u201d. Aquella formulaci\u00f3n aparentemente sencilla abri\u00f3 un [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":149570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-149583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De Ciudad Educadora a Comunidades Educadoras: el futuro de la educaci\u00f3n 360<\/title>\n<meta name=\"description\" content=\"C\u00f3mo las Ciudades Educadoras evolucionan hacia Comunidades Educadoras: v\u00ednculos, ocio, territorio y pol\u00edticas p\u00fablicas que garantizan una educaci\u00f3n ampliada para todos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Ciudad Educadora a Comunidades Educadoras: el futuro de la educaci\u00f3n 360\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo las Ciudades Educadoras evolucionan hacia Comunidades Educadoras: v\u00ednculos, ocio, territorio y pol\u00edticas p\u00fablicas que garantizan una educaci\u00f3n ampliada para todos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360\" \/>\n<meta property=\"og:site_name\" content=\"Equitat.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacioBofill?locale=es_ES\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T14:22:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T15:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.equitat.org\/app\/uploads\/2025\/12\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1002\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Cabanelas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FundacioBofill\" \/>\n<meta name=\"twitter:site\" content=\"@FundacioBofill\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Cabanelas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360\"},\"author\":{\"name\":\"Sergio Cabanelas\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#\\\/schema\\\/person\\\/8f55057659ab5ef931bf3e69e104677a\"},\"headline\":\"De Ciudad Educadora a Comunidades Educadoras: el futuro que ya est\u00e1 en marcha\",\"datePublished\":\"2025-12-01T14:22:13+00:00\",\"dateModified\":\"2025-12-03T15:28:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360\"},\"wordCount\":1878,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.equitat.org\\\/app\\\/uploads\\\/2025\\\/12\\\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360\",\"url\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360\",\"name\":\"De Ciudad Educadora a Comunidades Educadoras: el futuro de la educaci\u00f3n 360\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.equitat.org\\\/app\\\/uploads\\\/2025\\\/12\\\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg\",\"datePublished\":\"2025-12-01T14:22:13+00:00\",\"dateModified\":\"2025-12-03T15:28:37+00:00\",\"description\":\"C\u00f3mo las Ciudades Educadoras evolucionan hacia Comunidades Educadoras: v\u00ednculos, ocio, territorio y pol\u00edticas p\u00fablicas que garantizan una educaci\u00f3n ampliada para todos.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/ciutats-comunitats-educadores-educacio-360#primaryimage\",\"url\":\"https:\\\/\\\/www.equitat.org\\\/app\\\/uploads\\\/2025\\\/12\\\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.equitat.org\\\/app\\\/uploads\\\/2025\\\/12\\\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg\",\"width\":1500,\"height\":1002},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#website\",\"url\":\"https:\\\/\\\/www.equitat.org\\\/es\",\"name\":\"Equitat.org\",\"description\":\"educaci\u00f3 per canviar-ho tot\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.equitat.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#organization\",\"name\":\"Equitat\",\"url\":\"https:\\\/\\\/www.equitat.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.equitat.org\\\/app\\\/uploads\\\/2026\\\/04\\\/fundacio_jaume_bofill_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.equitat.org\\\/app\\\/uploads\\\/2026\\\/04\\\/fundacio_jaume_bofill_logo.jpg\",\"width\":200,\"height\":200,\"caption\":\"Equitat\"},\"image\":{\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacioBofill?locale=es_ES\",\"https:\\\/\\\/x.com\\\/FundacioBofill\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.equitat.org\\\/es#\\\/schema\\\/person\\\/8f55057659ab5ef931bf3e69e104677a\",\"name\":\"Sergio Cabanelas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66aba2892020195d70679b3324691de3310eb7a85ea10ba899cb6f022a2fd61c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66aba2892020195d70679b3324691de3310eb7a85ea10ba899cb6f022a2fd61c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66aba2892020195d70679b3324691de3310eb7a85ea10ba899cb6f022a2fd61c?s=96&d=mm&r=g\",\"caption\":\"Sergio Cabanelas\"},\"url\":\"https:\\\/\\\/www.equitat.org\\\/es\\\/blog\\\/author\\\/sergiocabanelas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Ciudad Educadora a Comunidades Educadoras: el futuro de la educaci\u00f3n 360","description":"C\u00f3mo las Ciudades Educadoras evolucionan hacia Comunidades Educadoras: v\u00ednculos, ocio, territorio y pol\u00edticas p\u00fablicas que garantizan una educaci\u00f3n ampliada para todos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360","og_locale":"es_ES","og_type":"article","og_title":"De Ciudad Educadora a Comunidades Educadoras: el futuro de la educaci\u00f3n 360","og_description":"C\u00f3mo las Ciudades Educadoras evolucionan hacia Comunidades Educadoras: v\u00ednculos, ocio, territorio y pol\u00edticas p\u00fablicas que garantizan una educaci\u00f3n ampliada para todos.","og_url":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360","og_site_name":"Equitat.org","article_publisher":"https:\/\/www.facebook.com\/FundacioBofill?locale=es_ES","article_published_time":"2025-12-01T14:22:13+00:00","article_modified_time":"2025-12-03T15:28:37+00:00","og_image":[{"width":1500,"height":1002,"url":"https:\/\/www.equitat.org\/app\/uploads\/2025\/12\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg","type":"image\/jpeg"}],"author":"Sergio Cabanelas","twitter_card":"summary_large_image","twitter_creator":"@FundacioBofill","twitter_site":"@FundacioBofill","twitter_misc":{"Escrito por":"Sergio Cabanelas","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360#article","isPartOf":{"@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360"},"author":{"name":"Sergio Cabanelas","@id":"https:\/\/www.equitat.org\/es#\/schema\/person\/8f55057659ab5ef931bf3e69e104677a"},"headline":"De Ciudad Educadora a Comunidades Educadoras: el futuro que ya est\u00e1 en marcha","datePublished":"2025-12-01T14:22:13+00:00","dateModified":"2025-12-03T15:28:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360"},"wordCount":1878,"commentCount":0,"publisher":{"@id":"https:\/\/www.equitat.org\/es#organization"},"image":{"@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360#primaryimage"},"thumbnailUrl":"https:\/\/www.equitat.org\/app\/uploads\/2025\/12\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360","url":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360","name":"De Ciudad Educadora a Comunidades Educadoras: el futuro de la educaci\u00f3n 360","isPartOf":{"@id":"https:\/\/www.equitat.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360#primaryimage"},"image":{"@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360#primaryimage"},"thumbnailUrl":"https:\/\/www.equitat.org\/app\/uploads\/2025\/12\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg","datePublished":"2025-12-01T14:22:13+00:00","dateModified":"2025-12-03T15:28:37+00:00","description":"C\u00f3mo las Ciudades Educadoras evolucionan hacia Comunidades Educadoras: v\u00ednculos, ocio, territorio y pol\u00edticas p\u00fablicas que garantizan una educaci\u00f3n ampliada para todos.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equitat.org\/es\/blog\/ciutats-comunitats-educadores-educacio-360#primaryimage","url":"https:\/\/www.equitat.org\/app\/uploads\/2025\/12\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg","contentUrl":"https:\/\/www.equitat.org\/app\/uploads\/2025\/12\/z1u-molins-de-rei_escola-josep-ma-madorell-112-1.jpg","width":1500,"height":1002},{"@type":"WebSite","@id":"https:\/\/www.equitat.org\/es#website","url":"https:\/\/www.equitat.org\/es","name":"Equitat.org","description":"educaci\u00f3 per canviar-ho tot","publisher":{"@id":"https:\/\/www.equitat.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.equitat.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.equitat.org\/es#organization","name":"Equitat","url":"https:\/\/www.equitat.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equitat.org\/es#\/schema\/logo\/image\/","url":"https:\/\/www.equitat.org\/app\/uploads\/2026\/04\/fundacio_jaume_bofill_logo.jpg","contentUrl":"https:\/\/www.equitat.org\/app\/uploads\/2026\/04\/fundacio_jaume_bofill_logo.jpg","width":200,"height":200,"caption":"Equitat"},"image":{"@id":"https:\/\/www.equitat.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacioBofill?locale=es_ES","https:\/\/x.com\/FundacioBofill"]},{"@type":"Person","@id":"https:\/\/www.equitat.org\/es#\/schema\/person\/8f55057659ab5ef931bf3e69e104677a","name":"Sergio Cabanelas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/66aba2892020195d70679b3324691de3310eb7a85ea10ba899cb6f022a2fd61c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/66aba2892020195d70679b3324691de3310eb7a85ea10ba899cb6f022a2fd61c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/66aba2892020195d70679b3324691de3310eb7a85ea10ba899cb6f022a2fd61c?s=96&d=mm&r=g","caption":"Sergio Cabanelas"},"url":"https:\/\/www.equitat.org\/es\/blog\/author\/sergiocabanelas"}]}},"_links":{"self":[{"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/posts\/149583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/comments?post=149583"}],"version-history":[{"count":1,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/posts\/149583\/revisions"}],"predecessor-version":[{"id":149585,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/posts\/149583\/revisions\/149585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/media\/149570"}],"wp:attachment":[{"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/media?parent=149583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/categories?post=149583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.equitat.org\/es\/wp-json\/wp\/v2\/tags?post=149583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}